{"id":6845,"date":"2023-09-28T10:18:42","date_gmt":"2023-09-28T08:18:42","guid":{"rendered":"https:\/\/alfrescovillas.com\/het-paradijs-verlaten\/"},"modified":"2024-02-18T12:00:09","modified_gmt":"2024-02-18T11:00:09","slug":"het-paradijs-verlaten","status":"publish","type":"post","link":"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/","title":{"rendered":"Het paradijs verlaten"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>We zijn erg verdrietig dat we het paradijs hebben verlaten. We hebben genoten van 5 heerlijke dagen hier in Lefkada ondanks de stormen. We kijken ernaar uit om snel terug te komen. Heel erg bedankt Barbara. Je bent de beste ambassadeur geweest. Tot snel (hoop ik).<\/p>\n<p>E. Molleja en familie uit Spanje, Villa Tranquility<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[41],"tags":[],"class_list":["post-6845","post","type-post","status-publish","format-standard","hentry","category-recencies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Het paradijs verlaten | Alfresco Villas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Het paradijs verlaten | Alfresco Villas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/\" \/>\n<meta property=\"og:site_name\" content=\"Alfresco Villas\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-28T08:18:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-18T11:00:09+00:00\" \/>\n<meta name=\"author\" content=\"Marjon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marjon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/het-paradijs-verlaten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/het-paradijs-verlaten\\\/\"},\"author\":{\"name\":\"Marjon\",\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/#\\\/schema\\\/person\\\/4bd3d0249481939b0984f8e1747a26f2\"},\"headline\":\"Het paradijs verlaten\",\"datePublished\":\"2023-09-28T08:18:42+00:00\",\"dateModified\":\"2024-02-18T11:00:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/het-paradijs-verlaten\\\/\"},\"wordCount\":305,\"publisher\":{\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/#organization\"},\"articleSection\":[\"Recencies\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/het-paradijs-verlaten\\\/\",\"url\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/het-paradijs-verlaten\\\/\",\"name\":\"Het paradijs verlaten | Alfresco Villas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/#website\"},\"datePublished\":\"2023-09-28T08:18:42+00:00\",\"dateModified\":\"2024-02-18T11:00:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/het-paradijs-verlaten\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/het-paradijs-verlaten\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/het-paradijs-verlaten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Het paradijs verlaten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/\",\"name\":\"Alfresco Villas\",\"description\":\"Droomvakantie in Griekenland\",\"publisher\":{\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/#organization\",\"name\":\"Alfresco Villas\",\"url\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alfrescovillas.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Alfresco-Villas-Logo-large.png\",\"contentUrl\":\"https:\\\/\\\/alfrescovillas.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Alfresco-Villas-Logo-large.png\",\"width\":355,\"height\":114,\"caption\":\"Alfresco Villas\"},\"image\":{\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/#\\\/schema\\\/person\\\/4bd3d0249481939b0984f8e1747a26f2\",\"name\":\"Marjon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e92374ae48017052bfa1eacfc63be59fadcc1b9530d4b175bb10692fdef9473b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e92374ae48017052bfa1eacfc63be59fadcc1b9530d4b175bb10692fdef9473b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e92374ae48017052bfa1eacfc63be59fadcc1b9530d4b175bb10692fdef9473b?s=96&d=mm&r=g\",\"caption\":\"Marjon\"},\"sameAs\":[\"https:\\\/\\\/alfrescovillas.com\"],\"url\":\"https:\\\/\\\/alfrescovillas.com\\\/nl\\\/author\\\/marjon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Het paradijs verlaten | Alfresco Villas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/","og_locale":"nl_NL","og_type":"article","og_title":"Het paradijs verlaten | Alfresco Villas","og_url":"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/","og_site_name":"Alfresco Villas","article_published_time":"2023-09-28T08:18:42+00:00","article_modified_time":"2024-02-18T11:00:09+00:00","author":"Marjon","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Marjon","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/#article","isPartOf":{"@id":"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/"},"author":{"name":"Marjon","@id":"https:\/\/alfrescovillas.com\/nl\/#\/schema\/person\/4bd3d0249481939b0984f8e1747a26f2"},"headline":"Het paradijs verlaten","datePublished":"2023-09-28T08:18:42+00:00","dateModified":"2024-02-18T11:00:09+00:00","mainEntityOfPage":{"@id":"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/"},"wordCount":305,"publisher":{"@id":"https:\/\/alfrescovillas.com\/nl\/#organization"},"articleSection":["Recencies"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/","url":"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/","name":"Het paradijs verlaten | Alfresco Villas","isPartOf":{"@id":"https:\/\/alfrescovillas.com\/nl\/#website"},"datePublished":"2023-09-28T08:18:42+00:00","dateModified":"2024-02-18T11:00:09+00:00","breadcrumb":{"@id":"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alfrescovillas.com\/nl\/het-paradijs-verlaten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alfrescovillas.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Het paradijs verlaten"}]},{"@type":"WebSite","@id":"https:\/\/alfrescovillas.com\/nl\/#website","url":"https:\/\/alfrescovillas.com\/nl\/","name":"Alfresco Villas","description":"Droomvakantie in Griekenland","publisher":{"@id":"https:\/\/alfrescovillas.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alfrescovillas.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/alfrescovillas.com\/nl\/#organization","name":"Alfresco Villas","url":"https:\/\/alfrescovillas.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/alfrescovillas.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/alfrescovillas.com\/wp-content\/uploads\/2022\/02\/Alfresco-Villas-Logo-large.png","contentUrl":"https:\/\/alfrescovillas.com\/wp-content\/uploads\/2022\/02\/Alfresco-Villas-Logo-large.png","width":355,"height":114,"caption":"Alfresco Villas"},"image":{"@id":"https:\/\/alfrescovillas.com\/nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/alfrescovillas.com\/nl\/#\/schema\/person\/4bd3d0249481939b0984f8e1747a26f2","name":"Marjon","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/e92374ae48017052bfa1eacfc63be59fadcc1b9530d4b175bb10692fdef9473b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e92374ae48017052bfa1eacfc63be59fadcc1b9530d4b175bb10692fdef9473b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e92374ae48017052bfa1eacfc63be59fadcc1b9530d4b175bb10692fdef9473b?s=96&d=mm&r=g","caption":"Marjon"},"sameAs":["https:\/\/alfrescovillas.com"],"url":"https:\/\/alfrescovillas.com\/nl\/author\/marjon\/"}]}},"_links":{"self":[{"href":"https:\/\/alfrescovillas.com\/nl\/wp-json\/wp\/v2\/posts\/6845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alfrescovillas.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alfrescovillas.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alfrescovillas.com\/nl\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/alfrescovillas.com\/nl\/wp-json\/wp\/v2\/comments?post=6845"}],"version-history":[{"count":7,"href":"https:\/\/alfrescovillas.com\/nl\/wp-json\/wp\/v2\/posts\/6845\/revisions"}],"predecessor-version":[{"id":6856,"href":"https:\/\/alfrescovillas.com\/nl\/wp-json\/wp\/v2\/posts\/6845\/revisions\/6856"}],"wp:attachment":[{"href":"https:\/\/alfrescovillas.com\/nl\/wp-json\/wp\/v2\/media?parent=6845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alfrescovillas.com\/nl\/wp-json\/wp\/v2\/categories?post=6845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alfrescovillas.com\/nl\/wp-json\/wp\/v2\/tags?post=6845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}